{"id":1842,"date":"2026-01-29T16:20:49","date_gmt":"2026-01-29T15:20:49","guid":{"rendered":"https:\/\/kvg-bus.de\/harburg\/?p=1842"},"modified":"2026-02-06T08:51:09","modified_gmt":"2026-02-06T07:51:09","slug":"hvv-hop-elbe-heide-nuevo-servicio-de-movilidad-a-la-carta-a-partir-del-2-de-febrero","status":"publish","type":"post","link":"https:\/\/kvg-bus.de\/harburg\/es\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/","title":{"rendered":"hvv hop Elbe-Heide: el 2 de febrero se pone en marcha un nuevo servicio de movilidad a la carta"},"content":{"rendered":"<p>Desde el <strong>2 de febrero de 2026<\/strong> complementado <strong>hvv hop Elbe-Heide<\/strong> transporte p\u00fablico en el municipio mancomunado de Salzhausen. El nuevo <strong>Servicio de transporte a la demanda<\/strong> permite viajes flexibles a la carta, sin horarios fijos y precisamente cuando las conexiones tradicionales de autob\u00fas no son adecuadas.<\/p>\n<p>Con hvv hop Elbe-Heide, le llamar\u00e1n c\u00f3modamente a trav\u00e9s de una aplicaci\u00f3n y le llevar\u00e1n de A a B <strong>a la tarifa normal de hvv, sin recargo por comodidad<\/strong>. Todo lo que necesita es un <strong>billete hvv<\/strong> o un <strong>Billete para Alemania<\/strong>.<\/p>\n<p>La lanzadera circula por el municipio mancomunado de Salzhausen y complementa as\u00ed los servicios de transporte existentes en las zonas rurales. En algunos casos, otros pasajeros con un destino similar tambi\u00e9n pueden subir al transbordador. <strong>Esto reduce la congesti\u00f3n de las carreteras y protege el medio ambiente<\/strong>.<\/p>\n<h3><strong>Nuestros horarios de servicio<\/strong><\/h3>\n<ul>\n<li><strong>De lunes a jueves:<\/strong> 5 - 23 en punto<\/li>\n<li><strong>El viernes:<\/strong> 5 - 2 en punto<\/li>\n<li><strong>S\u00e1bados y v\u00edsperas de festivos:<\/strong> 8 - 2 en punto<\/li>\n<li><strong>Domingos y festivos:<\/strong> 8 h - 23 h<\/li>\n<\/ul>\n<p>El servicio hvv hop Elbe-Heide le ofrece una alternativa de movilidad moderna y flexible en las zonas rurales, ideal para desplazarse al trabajo, ir de compras o realizar actividades de ocio.<\/p>\n<p>\ud83d\udcf1 La aplicaci\u00f3n para Android e iOS pronto estar\u00e1 disponible para su descarga. En cuanto est\u00e9 disponible, encontrar\u00e1s los enlaces aqu\u00ed<\/p>\n<p><span data-teams=\"true\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A partir del 2 de febrero de 2026, hvv hop Elbe-Heide complementar\u00e1 el transporte p\u00fablico local en el municipio mancomunado de Salzhausen. El nuevo servicio de lanzadera a la demanda permite viajes flexibles a la carta, sin horarios fijos y precisamente cuando las conexiones tradicionales de autob\u00fas no son adecuadas. Con hvv hop Elbe-Heide, se le puede llamar c\u00f3modamente a trav\u00e9s de la aplicaci\u00f3n y llevarle de A a B - con la tarifa regular de hvv, sin recargo de conveniencia. Todo lo que necesita es un billete v\u00e1lido de hvv o un billete alem\u00e1n. La lanzadera funciona en el municipio mancomunado de Salzhausen y complementa as\u00ed los servicios de transporte existentes en las zonas rurales. En algunos casos, otros pasajeros con un destino similar tambi\u00e9n pueden subir a la lanzadera, lo que reduce la congesti\u00f3n de las carreteras y protege el medio ambiente. Nuestros horarios de servicio Lunes - Jueves: 5 am - 11 pm Viernes: 5 am - 2 am S\u00e1bado y antes de d\u00edas festivos: 8 am - 2 am Domingo y en d\u00edas festivos: 8 am - 11 pm El hvv hop Elbe-Heide-Service le ofrece una alternativa de movilidad moderna y flexible en las zonas rurales - ideal para viajar al trabajo, ir de compras o actividades de ocio. \ud83d\udcf1 La aplicaci\u00f3n para Android e iOS podr\u00e1 descargarse en breve. En cuanto est\u00e9 disponible, encontrar\u00e1s los enlaces aqu\u00ed \u00a0<\/p>","protected":false},"author":4,"featured_media":4191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar - KVG Harburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-nuevo-servicio-de-movilidad-a-la-carta-a-partir-del-2-de-febrero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar - KVG Harburg\" \/>\n<meta property=\"og:description\" content=\"Ab dem 2. Februar 2026 erg\u00e4nzt hvv hop Elbe-Heide den \u00f6ffentlichen Nahverkehr in der Samtgemeinde Salzhausen. Der neue On-Demand-Shuttleservice erm\u00f6glicht flexible Fahrten nach Bedarf \u2013 ganz ohne festen Fahrplan und genau dann, wenn klassische Busverbindungen nicht passend sind. Mit hvv hop Elbe-Heide kannst du dich bequem per App abrufen lassen und wirst von A nach B gebracht \u2013 zum regul\u00e4ren hvv Tarif, ohne Komfortzuschlag. Alles, was du brauchst, ist ein g\u00fcltiges hvv Ticket oder ein Deutschlandticket. Das Shuttle f\u00e4hrt in der Samtgemeinde Salzhausen und erg\u00e4nzt so die bestehenden Verkehrsangebote im l\u00e4ndlichen Raum. Dabei steigt unter Umst\u00e4nden auch noch weitere Fahrg\u00e4ste mit \u00e4hnlichem Ziel ein \u2013 das entlastet Stra\u00dfen und schont die Umwelt. Unsere Bedienzeiten Montag \u2013 Donnerstag: 5 \u2013 23 Uhr Freitag: 5 \u2013 2 Uhr Samstag &amp; vor Feiertagen: 8 \u2013 2 Uhr Sonntag &amp; an Feiertagen: 8 \u2013 23 Uhr Der hvv hop Elbe-Heide-Service bietet dir eine zeitgem\u00e4\u00dfe, flexible Mobilit\u00e4tsalternative im l\u00e4ndlichen Bereich \u2013 ideal f\u00fcr den Weg zur Arbeit, zum Einkaufen oder zu Freizeitaktivit\u00e4ten. \ud83d\udcf1 Die App f\u00fcr Android und iOS steht bald zum Download bereit. Sobald sie verf\u00fcgbar ist, findest du hier die Links \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-nuevo-servicio-de-movilidad-a-la-carta-a-partir-del-2-de-febrero\/\" \/>\n<meta property=\"og:site_name\" content=\"KVG Harburg\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-29T15:20:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T07:51:09+00:00\" \/>\n<meta name=\"author\" content=\"sprager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sprager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/\"},\"author\":{\"name\":\"sprager\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#\\\/schema\\\/person\\\/b008f998d49926c8ddca013e5a810139\"},\"headline\":\"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar\",\"datePublished\":\"2026-01-29T15:20:49+00:00\",\"dateModified\":\"2026-02-06T07:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/\"},\"wordCount\":195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/\",\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/\",\"name\":\"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar - KVG Harburg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg\",\"datePublished\":\"2026-01-29T15:20:49+00:00\",\"dateModified\":\"2026-02-06T07:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#website\",\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/\",\"name\":\"KVG Harburg\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#organization\",\"name\":\"KVG Harburg\",\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/kvg_logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/kvg_logo-1.svg\",\"caption\":\"KVG Harburg\"},\"image\":{\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/#\\\/schema\\\/person\\\/b008f998d49926c8ddca013e5a810139\",\"name\":\"sprager\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"caption\":\"sprager\"},\"url\":\"https:\\\/\\\/kvg-bus.de\\\/harburg\\\/es\\\/author\\\/sprager\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"hvv hop Elbe-Heide: El nuevo servicio de movilidad a la demanda comienza el 2 de febrero - KVG Harburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-nuevo-servicio-de-movilidad-a-la-carta-a-partir-del-2-de-febrero\/","og_locale":"es_ES","og_type":"article","og_title":"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar - KVG Harburg","og_description":"Ab dem 2. Februar 2026 erg\u00e4nzt hvv hop Elbe-Heide den \u00f6ffentlichen Nahverkehr in der Samtgemeinde Salzhausen. Der neue On-Demand-Shuttleservice erm\u00f6glicht flexible Fahrten nach Bedarf \u2013 ganz ohne festen Fahrplan und genau dann, wenn klassische Busverbindungen nicht passend sind. Mit hvv hop Elbe-Heide kannst du dich bequem per App abrufen lassen und wirst von A nach B gebracht \u2013 zum regul\u00e4ren hvv Tarif, ohne Komfortzuschlag. Alles, was du brauchst, ist ein g\u00fcltiges hvv Ticket oder ein Deutschlandticket. Das Shuttle f\u00e4hrt in der Samtgemeinde Salzhausen und erg\u00e4nzt so die bestehenden Verkehrsangebote im l\u00e4ndlichen Raum. Dabei steigt unter Umst\u00e4nden auch noch weitere Fahrg\u00e4ste mit \u00e4hnlichem Ziel ein \u2013 das entlastet Stra\u00dfen und schont die Umwelt. Unsere Bedienzeiten Montag \u2013 Donnerstag: 5 \u2013 23 Uhr Freitag: 5 \u2013 2 Uhr Samstag &amp; vor Feiertagen: 8 \u2013 2 Uhr Sonntag &amp; an Feiertagen: 8 \u2013 23 Uhr Der hvv hop Elbe-Heide-Service bietet dir eine zeitgem\u00e4\u00dfe, flexible Mobilit\u00e4tsalternative im l\u00e4ndlichen Bereich \u2013 ideal f\u00fcr den Weg zur Arbeit, zum Einkaufen oder zu Freizeitaktivit\u00e4ten. \ud83d\udcf1 Die App f\u00fcr Android und iOS steht bald zum Download bereit. Sobald sie verf\u00fcgbar ist, findest du hier die Links \u00a0","og_url":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-nuevo-servicio-de-movilidad-a-la-carta-a-partir-del-2-de-febrero\/","og_site_name":"KVG Harburg","article_published_time":"2026-01-29T15:20:49+00:00","article_modified_time":"2026-02-06T07:51:09+00:00","author":"sprager","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sprager","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#article","isPartOf":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/"},"author":{"name":"sprager","@id":"https:\/\/kvg-bus.de\/harburg\/#\/schema\/person\/b008f998d49926c8ddca013e5a810139"},"headline":"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar","datePublished":"2026-01-29T15:20:49+00:00","dateModified":"2026-02-06T07:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/"},"wordCount":195,"commentCount":0,"publisher":{"@id":"https:\/\/kvg-bus.de\/harburg\/#organization"},"image":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#primaryimage"},"thumbnailUrl":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg","articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/","url":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/","name":"hvv hop Elbe-Heide: El nuevo servicio de movilidad a la demanda comienza el 2 de febrero - KVG Harburg","isPartOf":{"@id":"https:\/\/kvg-bus.de\/harburg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#primaryimage"},"image":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#primaryimage"},"thumbnailUrl":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg","datePublished":"2026-01-29T15:20:49+00:00","dateModified":"2026-02-06T07:51:09+00:00","breadcrumb":{"@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#primaryimage","url":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg","contentUrl":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/header-subsite_hvv-hop-Elbe-Heide_-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/kvg-bus.de\/harburg\/hvv-hop-elbe-heide-neuer-on-demand-mobilitaetsservice-startet-am-2-februar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kvg-bus.de\/harburg\/"},{"@type":"ListItem","position":2,"name":"hvv hop Elbe-Heide: Neuer On-Demand-Mobilit\u00e4tsservice startet am 2. Februar"}]},{"@type":"WebSite","@id":"https:\/\/kvg-bus.de\/harburg\/#website","url":"https:\/\/kvg-bus.de\/harburg\/","name":"KVG Harburg","description":"","publisher":{"@id":"https:\/\/kvg-bus.de\/harburg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kvg-bus.de\/harburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kvg-bus.de\/harburg\/#organization","name":"KVG Harburg","url":"https:\/\/kvg-bus.de\/harburg\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kvg-bus.de\/harburg\/#\/schema\/logo\/image\/","url":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/kvg_logo-1.svg","contentUrl":"https:\/\/kvg-bus.de\/harburg\/wp-content\/uploads\/sites\/14\/kvg_logo-1.svg","caption":"KVG Harburg"},"image":{"@id":"https:\/\/kvg-bus.de\/harburg\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/kvg-bus.de\/harburg\/#\/schema\/person\/b008f998d49926c8ddca013e5a810139","name":"sprager","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","caption":"sprager"},"url":"https:\/\/kvg-bus.de\/harburg\/es\/author\/sprager\/"}]}},"_links":{"self":[{"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/posts\/1842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/comments?post=1842"}],"version-history":[{"count":0,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/posts\/1842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/media?parent=1842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/categories?post=1842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kvg-bus.de\/harburg\/es\/wp-json\/wp\/v2\/tags?post=1842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}